{"id":9495,"date":"2024-12-20T07:44:37","date_gmt":"2024-12-20T07:44:37","guid":{"rendered":"https:\/\/www.tdhornor.net\/si-no-volvemos-a-vernos\/"},"modified":"2025-01-22T20:03:35","modified_gmt":"2025-01-22T20:03:35","slug":"si-no-volvemos-a-vernos","status":"publish","type":"post","link":"https:\/\/www.tdhornor.net\/es\/si-no-volvemos-a-vernos\/","title":{"rendered":"Si no volvemos a vernos&#8230;"},"content":{"rendered":"\n<div class=\"wp-block-group is-layout-constrained wp-block-group-is-layout-constrained\"><div class=\"wp-block-group__inner-container\">\n<h3 class=\"wp-block-heading\"><strong>SI NO VOLVEMOS A VERNOS&#8230;<\/strong><\/h3>\n\n\n\n<h5 class=\"wp-block-heading\" id=\"viewer-cdovs\"><strong>Es muy posible que nuestros caminos no vuelvan a cruzarse&#8230;<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"viewer-8vtcl\">Me alegro de que hayamos tenido la oportunidad de conocernos, pero soy consciente de que en este mundo tan acelerado puede que no volvamos a vernos. Aun as\u00ed, estoy deseando compartir contigo un descubrimiento que ha marcado una diferencia duradera en mi vida. Lo que tienes aqu\u00ed en tus manos lo resume todo.  <\/p>\n\n\n\n<h5 class=\"wp-block-heading\" id=\"viewer-7cput\"><strong>Descubrir nuestro prop\u00f3sito de estar aqu\u00ed<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"viewer-80hrl\">Se pretend\u00eda que la vida fuera mucho m\u00e1s que trabajar para pagar las facturas, vivir los fines de semana y marcar el tiempo entre el nacimiento y la muerte. La vida deb\u00eda ser una experiencia muy satisfactoria, no s\u00f3lo una existencia. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"viewer-26hh7\">De hecho, seg\u00fan un libro muy especial llamado Biblia, el prop\u00f3sito de la vida inclu\u00eda originalmente la amistad con Dios mismo en un mundo perfecto de amor y confianza. Fue posible porque \u00abDios cre\u00f3 [mankind] a Su propia imagen \u00ab1. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"viewer-fg190\">Comparti\u00f3 con ellos cualidades como las Suyas: inteligencia, conciencia, personalidad, habla, capacidad de elegir. Las cosas que a\u00fan hoy dan sentido a nuestras vidas. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"viewer-9af6d\">A pesar de un gran comienzo, lleg\u00f3 un momento en que el primer hombre y la primera mujer, Ad\u00e1n y Eva, eligieron ir en contra de una de las instrucciones que Dios les hab\u00eda dado. Las consecuencias fueron inmediatas. Su desobediencia -lo que la Biblia llama pecado- rompi\u00f3 la relaci\u00f3n que antes manten\u00edan con \u00c9l.2 Peor a\u00fan, el resultado final del pecado fue la muerte <em>f\u00edsica<\/em>. La muerte abri\u00f3 la puerta al resultado final del pecado, <em>la muerte eterna: la separaci\u00f3n<\/em> para siempre de Dios.    <\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"viewer-9jht6\">Desde sus d\u00edas hasta los nuestros, la historia de la humanidad puede resumirse as\u00ed: \u00abAunque conoc\u00edan a Dios, no le honraron como a Dios ni le dieron gracias, sino que se hicieron vanos de pensamiento y se les oscureci\u00f3 el necio coraz\u00f3n. Todos pecaron y est\u00e1n destituidos de la gloria de Dios&#8230;.La paga del pecado es la muerte. \u00ab3<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"viewer-2m1kl\">Todos hemos seguido los pasos de nuestros antepasados. Desobediencia. El enga\u00f1o. La mentira. Utilizaci\u00f3n de los dem\u00e1s. Amando el dinero. Sin tiempo para Dios en nuestras vidas. No es de extra\u00f1ar que nuestras vidas ofendan a <em>Dios<\/em>&#8230; \u00a1Ofendemos a nuestros <em>amigos<\/em>, aunque sean pecadores como nosotros!       <\/p>\n\n\n\n<h5 class=\"wp-block-heading\" id=\"viewer-5424n\"><strong>Restaurar una relaci\u00f3n rota<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"viewer-29au8\">Por desesperanzador que parezca, cuando la humanidad arruin\u00f3 las cosas, Dios ten\u00eda una soluci\u00f3n. Su plan: Hacer que alguien que nunca hab\u00eda obrado mal ocupara el lugar de todos los que hab\u00edan obrado mal&#8230; \u00a1Es decir, todos nosotros! Un sustituto inocente de los malhechores culpables.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"viewer-e7eut\">Hace dos mil a\u00f1os el plan se puso en marcha. Jesucristo, el Hijo de Dios, se convirti\u00f3 en uno de nosotros. En los 33 a\u00f1os que vivi\u00f3 como el \u00fanico Dios-Hombre, cumpli\u00f3 todos los requisitos y expectativas que Dios ten\u00eda para nosotros. Ni una sola vez pec\u00f3 contra Su Padre ni contra los que le rodeaban. En otras palabras, Jes\u00fas cumpli\u00f3 los requisitos para ser el <em>sustituto<\/em> perfecto de todos nosotros.    <\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"viewer-6agkc\">Su muerte en una cruz no fue el tr\u00e1gico final del mayor maestro del mundo; s\u00f3lo pareci\u00f3 \u00abs\u00f3lo\u00bb otra cruel ejecuci\u00f3n romana. En realidad, al morir Jes\u00fas cumpli\u00f3 Su deseo de asumir la pena de muerte eterna por todos nosotros. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"viewer-dn4ri\">La Biblia lo expresa as\u00ed \u00abDios muestra Su amor por nosotros en que, siendo todos pecadores, Cristo muri\u00f3 por nosotros&#8230;. para que todo el que crea en \u00c9l no perezca, sino que tenga vida eterna. Porque Dios no envi\u00f3 a su Hijo al mundo para condenar al mundo, sino para salvar al mundo por medio de \u00c9l. Cristo&#8230;padeci\u00f3 una sola vez por [our] pecados, el justo por los injustos, para llevarnos a Dios\u00bb. 4<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"viewer-710re\">Como \u00c9l es el \u00fanico Dios-Hombre, el sufrimiento de Jes\u00fas equival\u00eda al juicio eterno en el infierno que todos experimentar\u00edamos de otro modo. As\u00ed quiso restaurar el prop\u00f3sito original de Dios para nosotros. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"viewer-1h7fe\">La resurrecci\u00f3n de Jes\u00fas de entre los muertos tres d\u00edas despu\u00e9s de Su entierro (5) demostr\u00f3 que, al pagar la pena de muerte por nosotros, tambi\u00e9n hab\u00eda vencido a la muerte, no s\u00f3lo por S\u00ed mismo, sino por todos los que creen en \u00c9l. Eso significa que los que conf\u00edan en Dios para que perdone sus pecados tambi\u00e9n compartir\u00e1n la vida resucitada de Jes\u00fas para siempre en el Cielo. 6<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"viewer-8lh7c\">Hay m\u00e1s. Los que admiten que sus pecados causaron la muerte de Jes\u00fas y conf\u00edan en Dios para que los salve del juicio del pecado reciben vida eterna y espiritual en el momento en que creen. Jes\u00fas lo expres\u00f3 as\u00ed: \u00abHe venido para que [who trust in Me] tengan vida, y la tengan en abundancia.\u00bb 7  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"viewer-85g9o\">Es la restauraci\u00f3n de la relaci\u00f3n original perdida \u00a1y mucho m\u00e1s!<\/p>\n\n\n\n<h5 class=\"wp-block-heading\" id=\"viewer-7vuin\"><strong>Tomar una decisi\u00f3n personal<\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"viewer-bpq6d\">\u00c9sos son los hechos b\u00e1sicos de mi descubrimiento m\u00e1s importante. Aunque nunca volvamos a vernos, sigo queriendo que experimentes el prop\u00f3sito de Dios para ti. Dios te ofrece el perd\u00f3n y la vida eterna, pero <em>es tu decisi\u00f3n<\/em>. \u00bfQu\u00e9 elegir\u00e1s: prepararte para la eternidad a tu manera o seguir el camino de Dios?   <\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"viewer-aism9\">Si quieres aceptar la oferta de vida eterna de Dios, puedes expresar tu elecci\u00f3n con palabras como \u00e9stas:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><em>Querido Dios, reconozco que he pecado contra ti muchas veces en mi vida. Estoy convencido de que Jes\u00fas muri\u00f3 en mi lugar y asumi\u00f3 el juicio que merec\u00eda por mis pecados. Acepto tu oferta de perd\u00f3n. Quiero la nueva vida que Jes\u00fas promete a los que creen en \u00c9l. \u00a1Gracias por permitirme descubrir c\u00f3mo conocerte!    <\/em><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"viewer-7o15k\">Citas de la Biblia:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"viewer-23do3\">1 G\u00e9nesis 1:27<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"viewer-alf8s\">2 G\u00e9nesis 3<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"viewer-rivb\">3 Romanos 1:21, 3:23, 6:23,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"viewer-31teg\">4 Romanos 5:8, Juan 3:16-17, I Pedro 3:18<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"viewer-5lmih\">5 1 Corintios 15:1-8<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"viewer-bu5d9\">6 Juan 14:1-3<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"viewer-cj0k\">7 Juan 10:10.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"viewer-3041p\">Copiado de <a target=\"_blank\" href=\"http:\/\/litmin.org\/store\/products.php?prodid=1014&amp;do=list\" rel=\"noreferrer noopener\"><u>http:\/\/litmin.org\/store\/products.php?prodid=1014&amp;do=list<\/u><\/a><\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>SI NO VOLVEMOS A VERNOS&#8230; Es muy posible que nuestros caminos no vuelvan a cruzarse&#8230; Me alegro de que hayamos tenido la oportunidad de conocernos, pero soy consciente de que en este mundo tan acelerado puede que no volvamos a vernos. Aun as\u00ed, estoy deseando compartir contigo un descubrimiento que ha marcado una diferencia duradera [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":8925,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[47],"tags":[],"class_list":["post-9495","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conoce-a-dios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Si no volvemos a vernos | Descubrir el prop\u00f3sito de la vida<\/title>\n<meta name=\"description\" content=\"Explora c\u00f3mo restablecer tu relaci\u00f3n con Dios, descubrir el verdadero prop\u00f3sito de la vida y abrazar el perd\u00f3n y la vida eterna a trav\u00e9s de Jesucristo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tdhornor.net\/es\/si-no-volvemos-a-vernos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Si no volvemos a vernos | Descubrir el prop\u00f3sito de la vida\" \/>\n<meta property=\"og:description\" content=\"Explora c\u00f3mo restablecer tu relaci\u00f3n con Dios, descubrir el verdadero prop\u00f3sito de la vida y abrazar el perd\u00f3n y la vida eterna a trav\u00e9s de Jesucristo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tdhornor.net\/es\/si-no-volvemos-a-vernos\/\" \/>\n<meta property=\"og:site_name\" content=\"Tap &amp; Denise Hornor\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-20T07:44:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-22T20:03:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tdhornor.net\/wp-content\/uploads\/2022\/10\/Screenshot_2024-11-13_at_10.26.50_PM-removebg-preview-768x82-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"82\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/><meta property=\"og:image\" content=\"https:\/\/www.tdhornor.net\/wp-content\/uploads\/2024\/12\/3bb4ef_23d5656cfcb64fad93aac8d79dcfbb8dmv2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"292\" \/>\n\t<meta property=\"og:image:height\" content=\"219\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Designer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Designer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tdhornor.net\\\/es\\\/si-no-volvemos-a-vernos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tdhornor.net\\\/es\\\/si-no-volvemos-a-vernos\\\/\"},\"author\":{\"name\":\"Designer\",\"@id\":\"https:\\\/\\\/www.tdhornor.net\\\/es\\\/#\\\/schema\\\/person\\\/592bad9aabf15731971767675609ac0a\"},\"headline\":\"Si no volvemos a vernos&#8230;\",\"datePublished\":\"2024-12-20T07:44:37+00:00\",\"dateModified\":\"2025-01-22T20:03:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tdhornor.net\\\/es\\\/si-no-volvemos-a-vernos\\\/\"},\"wordCount\":1007,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tdhornor.net\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tdhornor.net\\\/es\\\/si-no-volvemos-a-vernos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tdhornor.net\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/3bb4ef_23d5656cfcb64fad93aac8d79dcfbb8dmv2.jpg\",\"articleSection\":[\"Conoce a Dios\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tdhornor.net\\\/es\\\/si-no-volvemos-a-vernos\\\/\",\"url\":\"https:\\\/\\\/www.tdhornor.net\\\/es\\\/si-no-volvemos-a-vernos\\\/\",\"name\":\"Si no volvemos a vernos | Descubrir el prop\u00f3sito de la vida\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tdhornor.net\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tdhornor.net\\\/es\\\/si-no-volvemos-a-vernos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tdhornor.net\\\/es\\\/si-no-volvemos-a-vernos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tdhornor.net\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/3bb4ef_23d5656cfcb64fad93aac8d79dcfbb8dmv2.jpg\",\"datePublished\":\"2024-12-20T07:44:37+00:00\",\"dateModified\":\"2025-01-22T20:03:35+00:00\",\"description\":\"Explora c\u00f3mo restablecer tu relaci\u00f3n con Dios, descubrir el verdadero prop\u00f3sito de la vida y abrazar el perd\u00f3n y la vida eterna a trav\u00e9s de Jesucristo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tdhornor.net\\\/es\\\/si-no-volvemos-a-vernos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tdhornor.net\\\/es\\\/si-no-volvemos-a-vernos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.tdhornor.net\\\/es\\\/si-no-volvemos-a-vernos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tdhornor.net\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/3bb4ef_23d5656cfcb64fad93aac8d79dcfbb8dmv2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tdhornor.net\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/3bb4ef_23d5656cfcb64fad93aac8d79dcfbb8dmv2.jpg\",\"width\":292,\"height\":219},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tdhornor.net\\\/es\\\/si-no-volvemos-a-vernos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tdhornor.net\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Si no volvemos a vernos&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tdhornor.net\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.tdhornor.net\\\/es\\\/\",\"name\":\"Tap &amp; Denise Hornor\",\"description\":\"Redeeming the Time and Reaching the Lost\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tdhornor.net\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tdhornor.net\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tdhornor.net\\\/es\\\/#organization\",\"name\":\"Tap &amp; Denise Hornor\",\"url\":\"https:\\\/\\\/www.tdhornor.net\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.tdhornor.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.tdhornor.net\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Screenshot_2024-11-13_at_10.26.50_PM-removebg-preview-768x82-1.png\",\"contentUrl\":\"https:\\\/\\\/www.tdhornor.net\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Screenshot_2024-11-13_at_10.26.50_PM-removebg-preview-768x82-1.png\",\"width\":768,\"height\":82,\"caption\":\"Tap &amp; Denise Hornor\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tdhornor.net\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tdhornor.net\\\/es\\\/#\\\/schema\\\/person\\\/592bad9aabf15731971767675609ac0a\",\"name\":\"Designer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ce1fd7ecd5ec8ba0d15a84f6a827ea7c0b9f5cfc57718ea4e148c8366b2fc87?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ce1fd7ecd5ec8ba0d15a84f6a827ea7c0b9f5cfc57718ea4e148c8366b2fc87?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ce1fd7ecd5ec8ba0d15a84f6a827ea7c0b9f5cfc57718ea4e148c8366b2fc87?s=96&d=mm&r=g\",\"caption\":\"Designer\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Si no volvemos a vernos | Descubrir el prop\u00f3sito de la vida","description":"Explora c\u00f3mo restablecer tu relaci\u00f3n con Dios, descubrir el verdadero prop\u00f3sito de la vida y abrazar el perd\u00f3n y la vida eterna a trav\u00e9s de Jesucristo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tdhornor.net\/es\/si-no-volvemos-a-vernos\/","og_locale":"es_ES","og_type":"article","og_title":"Si no volvemos a vernos | Descubrir el prop\u00f3sito de la vida","og_description":"Explora c\u00f3mo restablecer tu relaci\u00f3n con Dios, descubrir el verdadero prop\u00f3sito de la vida y abrazar el perd\u00f3n y la vida eterna a trav\u00e9s de Jesucristo.","og_url":"https:\/\/www.tdhornor.net\/es\/si-no-volvemos-a-vernos\/","og_site_name":"Tap &amp; Denise Hornor","article_published_time":"2024-12-20T07:44:37+00:00","article_modified_time":"2025-01-22T20:03:35+00:00","og_image":[{"width":768,"height":82,"url":"https:\/\/www.tdhornor.net\/wp-content\/uploads\/2022\/10\/Screenshot_2024-11-13_at_10.26.50_PM-removebg-preview-768x82-1.png","type":"image\/png"},{"width":292,"height":219,"url":"https:\/\/www.tdhornor.net\/wp-content\/uploads\/2024\/12\/3bb4ef_23d5656cfcb64fad93aac8d79dcfbb8dmv2.jpg","type":"image\/jpeg"}],"author":"Designer","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Designer","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tdhornor.net\/es\/si-no-volvemos-a-vernos\/#article","isPartOf":{"@id":"https:\/\/www.tdhornor.net\/es\/si-no-volvemos-a-vernos\/"},"author":{"name":"Designer","@id":"https:\/\/www.tdhornor.net\/es\/#\/schema\/person\/592bad9aabf15731971767675609ac0a"},"headline":"Si no volvemos a vernos&#8230;","datePublished":"2024-12-20T07:44:37+00:00","dateModified":"2025-01-22T20:03:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tdhornor.net\/es\/si-no-volvemos-a-vernos\/"},"wordCount":1007,"publisher":{"@id":"https:\/\/www.tdhornor.net\/es\/#organization"},"image":{"@id":"https:\/\/www.tdhornor.net\/es\/si-no-volvemos-a-vernos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tdhornor.net\/wp-content\/uploads\/2024\/12\/3bb4ef_23d5656cfcb64fad93aac8d79dcfbb8dmv2.jpg","articleSection":["Conoce a Dios"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.tdhornor.net\/es\/si-no-volvemos-a-vernos\/","url":"https:\/\/www.tdhornor.net\/es\/si-no-volvemos-a-vernos\/","name":"Si no volvemos a vernos | Descubrir el prop\u00f3sito de la vida","isPartOf":{"@id":"https:\/\/www.tdhornor.net\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tdhornor.net\/es\/si-no-volvemos-a-vernos\/#primaryimage"},"image":{"@id":"https:\/\/www.tdhornor.net\/es\/si-no-volvemos-a-vernos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tdhornor.net\/wp-content\/uploads\/2024\/12\/3bb4ef_23d5656cfcb64fad93aac8d79dcfbb8dmv2.jpg","datePublished":"2024-12-20T07:44:37+00:00","dateModified":"2025-01-22T20:03:35+00:00","description":"Explora c\u00f3mo restablecer tu relaci\u00f3n con Dios, descubrir el verdadero prop\u00f3sito de la vida y abrazar el perd\u00f3n y la vida eterna a trav\u00e9s de Jesucristo.","breadcrumb":{"@id":"https:\/\/www.tdhornor.net\/es\/si-no-volvemos-a-vernos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tdhornor.net\/es\/si-no-volvemos-a-vernos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.tdhornor.net\/es\/si-no-volvemos-a-vernos\/#primaryimage","url":"https:\/\/www.tdhornor.net\/wp-content\/uploads\/2024\/12\/3bb4ef_23d5656cfcb64fad93aac8d79dcfbb8dmv2.jpg","contentUrl":"https:\/\/www.tdhornor.net\/wp-content\/uploads\/2024\/12\/3bb4ef_23d5656cfcb64fad93aac8d79dcfbb8dmv2.jpg","width":292,"height":219},{"@type":"BreadcrumbList","@id":"https:\/\/www.tdhornor.net\/es\/si-no-volvemos-a-vernos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tdhornor.net\/es\/"},{"@type":"ListItem","position":2,"name":"Si no volvemos a vernos&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.tdhornor.net\/es\/#website","url":"https:\/\/www.tdhornor.net\/es\/","name":"Tap &amp; Denise Hornor","description":"Redeeming the Time and Reaching the Lost","publisher":{"@id":"https:\/\/www.tdhornor.net\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tdhornor.net\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.tdhornor.net\/es\/#organization","name":"Tap &amp; Denise Hornor","url":"https:\/\/www.tdhornor.net\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.tdhornor.net\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.tdhornor.net\/wp-content\/uploads\/2022\/10\/Screenshot_2024-11-13_at_10.26.50_PM-removebg-preview-768x82-1.png","contentUrl":"https:\/\/www.tdhornor.net\/wp-content\/uploads\/2022\/10\/Screenshot_2024-11-13_at_10.26.50_PM-removebg-preview-768x82-1.png","width":768,"height":82,"caption":"Tap &amp; Denise Hornor"},"image":{"@id":"https:\/\/www.tdhornor.net\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.tdhornor.net\/es\/#\/schema\/person\/592bad9aabf15731971767675609ac0a","name":"Designer","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4ce1fd7ecd5ec8ba0d15a84f6a827ea7c0b9f5cfc57718ea4e148c8366b2fc87?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4ce1fd7ecd5ec8ba0d15a84f6a827ea7c0b9f5cfc57718ea4e148c8366b2fc87?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4ce1fd7ecd5ec8ba0d15a84f6a827ea7c0b9f5cfc57718ea4e148c8366b2fc87?s=96&d=mm&r=g","caption":"Designer"}}]}},"_links":{"self":[{"href":"https:\/\/www.tdhornor.net\/es\/wp-json\/wp\/v2\/posts\/9495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tdhornor.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tdhornor.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tdhornor.net\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tdhornor.net\/es\/wp-json\/wp\/v2\/comments?post=9495"}],"version-history":[{"count":1,"href":"https:\/\/www.tdhornor.net\/es\/wp-json\/wp\/v2\/posts\/9495\/revisions"}],"predecessor-version":[{"id":9496,"href":"https:\/\/www.tdhornor.net\/es\/wp-json\/wp\/v2\/posts\/9495\/revisions\/9496"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tdhornor.net\/es\/wp-json\/wp\/v2\/media\/8925"}],"wp:attachment":[{"href":"https:\/\/www.tdhornor.net\/es\/wp-json\/wp\/v2\/media?parent=9495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tdhornor.net\/es\/wp-json\/wp\/v2\/categories?post=9495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tdhornor.net\/es\/wp-json\/wp\/v2\/tags?post=9495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}